{"id":338,"date":"2015-11-23T09:09:49","date_gmt":"2015-11-23T09:09:49","guid":{"rendered":"http:\/\/www.retowidmer.ch\/?p=338"},"modified":"2015-11-23T09:15:52","modified_gmt":"2015-11-23T09:15:52","slug":"roboter-am-arbeitsplatz-wo-die-maschine-uns-ersetzt","status":"publish","type":"post","link":"https:\/\/www.retowidmer.ch\/blog\/roboter-am-arbeitsplatz-wo-die-maschine-uns-ersetzt\/","title":{"rendered":"Roboter am Arbeitsplatz: Wo die Maschine uns ersetzt"},"content":{"rendered":"<p>In 20 Jahren soll die H\u00e4lfte unserer Jobs verschwunden sein, sogar das \u00e4lteste Gewerbe der Welt, die Prostitution, ist nicht mehr sicher vor Robotern. Ich habe in der Sendung &#8222;Input&#8220; auf SRF 3\u00a0gecheckt, ob&#8217;s so schlimm wird und in welchen Branchen es dank der neuen Roboter f\u00fcr unsere Gesellschaft auch Chancen gibt.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-338-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.retowidmer.ch\/blog\/wp-content\/uploads\/2015\/11\/22112015_roboter.mp3?_=1\" \/><a href=\"https:\/\/www.retowidmer.ch\/blog\/wp-content\/uploads\/2015\/11\/22112015_roboter.mp3\">https:\/\/www.retowidmer.ch\/blog\/wp-content\/uploads\/2015\/11\/22112015_roboter.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.srf.ch\/sendungen\/input\/roboter-am-arbeitsplatz-wo-die-maschine-uns-ersetzt\" target=\"_blank\">Mehr Infos<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In 20 Jahren soll die H\u00e4lfte unserer Jobs verschwunden sein, sogar das \u00e4lteste Gewerbe der Welt, die Prostitution, ist nicht mehr sicher vor Robotern. Ich habe in der Sendung &#8222;Input&#8220; auf SRF 3\u00a0gecheckt, ob&#8217;s so schlimm wird und in welchen Branchen es dank der neuen Roboter f\u00fcr unsere Gesellschaft auch Chancen gibt. &nbsp; Mehr Infos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":339,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hintergrund","post-preview"],"_links":{"self":[{"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/posts\/338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/comments?post=338"}],"version-history":[{"count":0,"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/posts\/338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/media\/339"}],"wp:attachment":[{"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/media?parent=338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/categories?post=338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retowidmer.ch\/blog\/wp-json\/wp\/v2\/tags?post=338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}